{"id":8529,"date":"2024-06-25T16:41:35","date_gmt":"2024-06-25T14:41:35","guid":{"rendered":"https:\/\/update24.rugefehsenfeld.de\/?post_type=kompetenz&#038;p=8529"},"modified":"2024-07-03T15:06:43","modified_gmt":"2024-07-03T13:06:43","slug":"tax-audits-and-tax-court","status":"publish","type":"kompetenz","link":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court","title":{"rendered":"Tax Audits and Tax Court"},"featured_media":7671,"template":"","meta":{"_acf_changed":false},"kategorien":[43],"class_list":["post-8529","kompetenz","type-kompetenz","status-publish","has-post-thumbnail","hentry","kategorien-tax-advisory"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tax Audits and Tax Court | RUGE FEHSENFELD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tax Audits and Tax Court | RUGE FEHSENFELD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court\" \/>\n<meta property=\"og:site_name\" content=\"RUGE FEHSENFELD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rugefehsenfeld\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-03T13:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rugefehsenfeld.de\/wp-content\/uploads\/20170901_RugeFehsenfeld_040_S.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court\",\"url\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court\",\"name\":\"Tax Audits and Tax Court | RUGE FEHSENFELD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/wp-content\\\/uploads\\\/20170901_RugeFehsenfeld_040_S.jpg\",\"datePublished\":\"2024-06-25T14:41:35+00:00\",\"dateModified\":\"2024-07-03T13:06:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court#primaryimage\",\"url\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/wp-content\\\/uploads\\\/20170901_RugeFehsenfeld_040_S.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/wp-content\\\/uploads\\\/20170901_RugeFehsenfeld_040_S.jpg\",\"width\":\"1500\",\"height\":\"1001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\\\/tax-audits-and-tax-court#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tax Advisory\",\"item\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/tax-advisory\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tax Audits and Tax Court\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/\",\"name\":\"RUGE FEHSENFELD\",\"description\":\"Rechtsanw\u00e4lte, Steuerberater, Fachanw\u00e4lte\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/#organization\"},\"alternateName\":\"RUGE FEHSENFELD | Rechtsanw\u00e4lte, Steuerberater & Fachanw\u00e4lte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/#organization\",\"name\":\"RUGE FEHSENFELD\",\"alternateName\":\"RF\",\"url\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/wp-content\\\/uploads\\\/ruge-fehsenfeld-favicon.svg\",\"contentUrl\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/wp-content\\\/uploads\\\/ruge-fehsenfeld-favicon.svg\",\"width\":80,\"height\":80,\"caption\":\"RUGE FEHSENFELD\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rugefehsenfeld.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rugefehsenfeld\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rugefehsenfeld\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ruge-fehsenfeld-llp\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/rugefehsenfeld\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tax Audits and Tax Court | RUGE FEHSENFELD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court","og_locale":"en_US","og_type":"article","og_title":"Tax Audits and Tax Court | RUGE FEHSENFELD","og_url":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court","og_site_name":"RUGE FEHSENFELD","article_publisher":"https:\/\/www.facebook.com\/rugefehsenfeld\/","article_modified_time":"2024-07-03T13:06:43+00:00","og_image":[{"width":1500,"height":1001,"url":"https:\/\/www.rugefehsenfeld.de\/wp-content\/uploads\/20170901_RugeFehsenfeld_040_S.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court","url":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court","name":"Tax Audits and Tax Court | RUGE FEHSENFELD","isPartOf":{"@id":"https:\/\/www.rugefehsenfeld.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court#primaryimage"},"image":{"@id":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court#primaryimage"},"thumbnailUrl":"https:\/\/www.rugefehsenfeld.de\/wp-content\/uploads\/20170901_RugeFehsenfeld_040_S.jpg","datePublished":"2024-06-25T14:41:35+00:00","dateModified":"2024-07-03T13:06:43+00:00","breadcrumb":{"@id":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court#primaryimage","url":"https:\/\/www.rugefehsenfeld.de\/wp-content\/uploads\/20170901_RugeFehsenfeld_040_S.jpg","contentUrl":"https:\/\/www.rugefehsenfeld.de\/wp-content\/uploads\/20170901_RugeFehsenfeld_040_S.jpg","width":"1500","height":"1001"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory\/tax-audits-and-tax-court#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rugefehsenfeld.de\/en"},{"@type":"ListItem","position":2,"name":"Tax Advisory","item":"https:\/\/www.rugefehsenfeld.de\/en\/tax-advisory"},{"@type":"ListItem","position":3,"name":"Tax Audits and Tax Court"}]},{"@type":"WebSite","@id":"https:\/\/www.rugefehsenfeld.de\/en\/#website","url":"https:\/\/www.rugefehsenfeld.de\/en\/","name":"RUGE FEHSENFELD","description":"Rechtsanw\u00e4lte, Steuerberater, Fachanw\u00e4lte","publisher":{"@id":"https:\/\/www.rugefehsenfeld.de\/en\/#organization"},"alternateName":"RUGE FEHSENFELD | Rechtsanw\u00e4lte, Steuerberater & Fachanw\u00e4lte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rugefehsenfeld.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rugefehsenfeld.de\/en\/#organization","name":"RUGE FEHSENFELD","alternateName":"RF","url":"https:\/\/www.rugefehsenfeld.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rugefehsenfeld.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rugefehsenfeld.de\/wp-content\/uploads\/ruge-fehsenfeld-favicon.svg","contentUrl":"https:\/\/www.rugefehsenfeld.de\/wp-content\/uploads\/ruge-fehsenfeld-favicon.svg","width":80,"height":80,"caption":"RUGE FEHSENFELD"},"image":{"@id":"https:\/\/www.rugefehsenfeld.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rugefehsenfeld\/","https:\/\/www.instagram.com\/rugefehsenfeld\/","https:\/\/www.linkedin.com\/company\/ruge-fehsenfeld-llp\/","https:\/\/www.xing.com\/pages\/rugefehsenfeld"]}]}},"_links":{"self":[{"href":"https:\/\/www.rugefehsenfeld.de\/en\/wp-json\/wp\/v2\/kompetenz\/8529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rugefehsenfeld.de\/en\/wp-json\/wp\/v2\/kompetenz"}],"about":[{"href":"https:\/\/www.rugefehsenfeld.de\/en\/wp-json\/wp\/v2\/types\/kompetenz"}],"version-history":[{"count":0,"href":"https:\/\/www.rugefehsenfeld.de\/en\/wp-json\/wp\/v2\/kompetenz\/8529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rugefehsenfeld.de\/en\/wp-json\/wp\/v2\/media\/7671"}],"wp:attachment":[{"href":"https:\/\/www.rugefehsenfeld.de\/en\/wp-json\/wp\/v2\/media?parent=8529"}],"wp:term":[{"taxonomy":"kategorien","embeddable":true,"href":"https:\/\/www.rugefehsenfeld.de\/en\/wp-json\/wp\/v2\/kategorien?post=8529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}